{"id":96562,"date":"2024-07-03T10:52:37","date_gmt":"2024-07-03T08:52:37","guid":{"rendered":"https:\/\/beckertoys.com\/producto\/barbie-the-movie-de-2022\/"},"modified":"2026-07-15T00:28:55","modified_gmt":"2026-07-14T22:28:55","slug":"barbie-the-movie-de-2022","status":"publish","type":"product","link":"https:\/\/beckertoys.com\/fr\/mattel\/barbie-the-movie-de-2022\/","title":{"rendered":"Barbie The Movie de 2022"},"content":{"rendered":"<ul class=\"a-unordered-list a-vertical a-spacing-mini\">\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">Emportez chez vous une partie du film de Barbie con esta poup\u00e9e Barbie pour collectionneurs; Con su robe rosa de cuadros, est pr\u00eate \u00e0 profiter de un d\u00eda inolvidable en Barbie Land<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">La poup\u00e9e Barbie porte un robe de cuadros rosa y blanco de inspiraci\u00f3n retro con cintur\u00f3n a juego y falda plisada<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">Lleva su larga melena rubia semirrecogida y sujeta con un lazo rosa, que deja ver sus pendientes de margarita<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">\u00a1Es igual que la Barbie de la pel\u00edcula con su collar de margaritas! Una adorable pulsera rosa y unos chaussures de tac\u00f3n rosas adornados con un coraz\u00f3n ponen el broche final al look<\/span><\/li>\n<li class=\"a-spacing-mini\"><span class=\"a-list-item\">Esta poup\u00e9e articulada viene en un embalaje coleccionable de la pel\u00edcula de Barbie; \u00a1Echa un vistazo a la collection entera para descubrir m\u00e1s ideas de regalo; Se venden por separado y est\u00e1n sujetas a disponibilidad<\/span><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><span data-sheets-root=\"1\" data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;2022 BARBIE THE MOVIE Margot Robbie&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:16961,&quot;3&quot;:{&quot;1&quot;:0},&quot;9&quot;:0,&quot;12&quot;:0,&quot;17&quot;:1}\">Poup\u00e9e BARBIE THE MOVIE Margot Robbie de 2022. Neuve.<\/span><\/p>\n","protected":false},"featured_media":13814,"template":"","meta":{"_acf_changed":false,"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":""},"product_brand":[241],"product_cat":[283,282],"product_tag":[],"class_list":["post-96562","product","type-product","status-publish","has-post-thumbnail","product_brand-mattel","product_cat-barbie-de-collection","product_cat-poupees-barbie","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","wc-has-gallery","first","instock","sold-individually","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/beckertoys.com\/fr\/wp-json\/wp\/v2\/product\/96562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beckertoys.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/beckertoys.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/beckertoys.com\/fr\/wp-json\/wp\/v2\/product\/96562\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beckertoys.com\/fr\/wp-json\/wp\/v2\/media\/13814"}],"wp:attachment":[{"href":"https:\/\/beckertoys.com\/fr\/wp-json\/wp\/v2\/media?parent=96562"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/beckertoys.com\/fr\/wp-json\/wp\/v2\/product_brand?post=96562"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/beckertoys.com\/fr\/wp-json\/wp\/v2\/product_cat?post=96562"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/beckertoys.com\/fr\/wp-json\/wp\/v2\/product_tag?post=96562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}