{"id":101899,"date":"2026-05-30T12:59:54","date_gmt":"2026-05-30T10:59:54","guid":{"rendered":"https:\/\/beckertoys.com\/?post_type=product&p=101899"},"modified":"2026-06-01T19:59:54","modified_gmt":"2026-06-01T17:59:54","slug":"barbie-swiss-del-1983","status":"publish","type":"product","link":"https:\/\/beckertoys.com\/it\/mattel\/barbie-swiss-del-1983\/","title":{"rendered":"Barbie Swiss del 1983"},"content":{"rendered":"<h4 data-section-id=\"1h26571\" data-start=\"0\" data-end=\"60\">Barbie Swiss del 1983 Dolls of the World con scatola originale<\/h4>\n<h5 data-section-id=\"3heqsr\" data-start=\"62\" data-end=\"77\">Descrizione<\/h5>\n<p data-start=\"79\" data-end=\"412\">Bambola <strong data-start=\"86\" data-end=\"110\">Barbie Swiss del 1983<\/strong>, appartenente alla linea <strong data-start=\"137\" data-end=\"159\">Dolls of the World<\/strong> di Mattel, presentata nella sua scatola originale. \u00c8 un pezzo particolarmente interessante per collezionisti di Barbie vintage e de ediciones internacionales, al formar parte de una de las lineas cl\u00e1sicas dedicadas a representar pa\u00edses e trajes tradicionales.<\/p>\n<p data-start=\"414\" data-end=\"863\">La bambola luce un traje ispirato a la vestimenta tradicional suiza, con gonna roja estampada, corpi\u00f1o blu con lazada dorata e blusa bianca de mangas abullonadas. Presenta capelli rubio peinado en dos coletas con lazos rossos, ojos blues e una imagen general muy representativa de las ediciones Dolls of the World de principios de los anni 80. La scatola muestra el dise\u00f1o rosa cl\u00e1sico con el texto <strong data-start=\"812\" data-end=\"828\">Swiss Barbie<\/strong> e gr\u00e1ficos relacionados con Suiza.<\/p>\n<p data-start=\"865\" data-end=\"1245\" data-is-last-node=\"\" data-is-only-node=\"\">Su valor coleccionable si distingue per conservarse <strong data-start=\"912\" data-end=\"932\">en scatola originale<\/strong> e da tratarse de una Barbie vintage del 1983 dentro de la linea internacional di Mattel. La scatola se aprecia completa, aunque presenta desgaste visible da almacenamiento, includendo roces, dobleces, marcas en el pl\u00e1stico, zonas arrugadas, esquinas da\u00f1adas e cinta adhesiva visible en la parte trasera e superior.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bambola Vintage de collezione Dolls of the World &#8211; Barbie Swiss del 1983 Suiza. Nuova, mai rimossa dalla scatola. Scatola danneggiata.<\/p>\n<p>Articolo di seconda mano.<\/p>\n","protected":false},"featured_media":101900,"template":"","meta":{"_acf_changed":false,"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":""},"product_brand":[227],"product_cat":[230,231],"product_tag":[],"class_list":["post-101899","product","type-product","status-publish","has-post-thumbnail","product_brand-mattel","product_cat-bambole-barbie","product_cat-collezione-barbie","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","wc-has-gallery","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/product\/101899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/product\/101899\/revisions"}],"predecessor-version":[{"id":102552,"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/product\/101899\/revisions\/102552"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/media\/101900"}],"wp:attachment":[{"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/media?parent=101899"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/product_brand?post=101899"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/product_cat?post=101899"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/product_tag?post=101899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}