{"id":58760,"date":"2026-02-23T19:59:34","date_gmt":"2026-02-23T18:59:34","guid":{"rendered":"https:\/\/beckertoys.com\/producto\/1997-barbie-native-american-fourth-edition-e-unedizione-speciale-della-celebre-barbie-lanciata-da-mattel-come-parte-della-serie-dolls-of-the-world-la-bambola-misura-circa-30-cm-ed-e-pensata\/"},"modified":"2026-07-15T00:29:06","modified_gmt":"2026-07-14T22:29:06","slug":"1997-barbie-native-american-fourth-edition-e-unedizione-speciale-della-celebre-barbie-lanciata-da-mattel-come-parte-della-serie-dolls-of-the-world-la-bambola-misura-circa-30-cm-ed-e-pensata","status":"publish","type":"product","link":"https:\/\/beckertoys.com\/it\/mattel\/1997-barbie-native-american-fourth-edition-e-unedizione-speciale-della-celebre-barbie-lanciata-da-mattel-come-parte-della-serie-dolls-of-the-world-la-bambola-misura-circa-30-cm-ed-e-pensata\/","title":{"rendered":"<strong>1997 Barbie Native American Fourth Edition<\/strong> \u00e8 un\u2019edizione speciale della celebre Barbie, lanciata da Mattel come parte della serie <strong>Dolls of the World<\/strong>. La bambola misura circa 30 cm ed \u00e8 pensata per rappresentare una principessa nativa americana. Indossa poncho marrone, gonna decorata, mocassini e gioielli ispirati alla cultura nativa. Include pettine e base espositiva, ed \u00e8 ideale per collezionisti interessati alla diversit\u00e0 culturale nelle bambole Barbie."},"content":{"rendered":"<p><strong>1997 Barbie Native American Fourth Edition<\/strong> \u00e8 un\u2019edizione speciale della celebre Barbie, lanciata da Mattel come parte della serie <strong>Dolls of the World<\/strong>. La bambola misura circa 30 cm ed \u00e8 pensata per rappresentare una principessa nativa americana. Indossa poncho marrone, gonna decorata, mocassini e gioielli ispirati alla cultura nativa. Include pettine e base espositiva, ed \u00e8 ideale per collezionisti interessati alla diversit\u00e0 culturale nelle bambole Barbie.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>1997 Barbie Native American Fourth Edition<\/strong> \u00e8 un\u2019edizione speciale della celebre Barbie, lanciata da Mattel come parte della serie <strong>Dolls of the World<\/strong>. La bambola misura circa 30 cm ed \u00e8 pensata per rappresentare una principessa nativa americana. Indossa poncho marrone, gonna decorata, mocassini e gioielli ispirati alla cultura nativa. Include pettine e base espositiva, ed \u00e8 ideale per collezionisti interessati alla diversit\u00e0 culturale nelle bambole Barbie.<\/p>\n","protected":false},"featured_media":58769,"template":"","meta":{"_acf_changed":false,"_jet_sm_ready_style":"","_jet_sm_style":"","_jet_sm_controls_values":"","_jet_sm_fonts_collection":"","_jet_sm_fonts_links":""},"product_brand":[227],"product_cat":[230,231],"product_tag":[],"class_list":["post-58760","product","type-product","status-publish","has-post-thumbnail","product_brand-mattel","product_cat-bambole-barbie","product_cat-collezione-barbie","sales-flash-overlay","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","wc-has-gallery","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/product\/58760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/product\/58760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/media\/58769"}],"wp:attachment":[{"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/media?parent=58760"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/product_brand?post=58760"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/product_cat?post=58760"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/beckertoys.com\/it\/wp-json\/wp\/v2\/product_tag?post=58760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}